{"id":8575,"date":"2015-09-15T11:59:27","date_gmt":"2015-09-15T04:59:27","guid":{"rendered":"http:\/\/larts.rmutp.ac.th\/2554\/?p=8575"},"modified":"2015-09-23T14:01:33","modified_gmt":"2015-09-23T07:01:33","slug":"%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%95%e0%b8%a3-3","status":"publish","type":"post","link":"https:\/\/larts.rmutp.ac.th\/2554\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%a8%e0%b8%b4%e0%b8%a5%e0%b8%9b%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-%e0%b8%a3%e0%b8%b1%e0%b8%9a%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%95%e0%b8%a3-3\/","title":{"rendered":"\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557"},"content":{"rendered":"<p><!--more--><\/p>\n<div id=\"su_slider_6a56e831917d8\" class=\"su-slider su-slider-centered su-slider-pages-yes su-slider-responsive-yes\" style=\"width:100%\" data-autoplay=\"3000\" data-speed=\"600\" data-mousewheel=\"true\"><div class=\"su-slider-slides\"><div class=\"su-slider-slide\"><a><img decoding=\"async\" data-src=\"https:\/\/larts.rmutp.ac.th\/2554\/wp-content\/uploads\/2015\/09\/\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19_6808-700x420.jpg\" alt=\"\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 700px; --smush-placeholder-aspect-ratio: 700\/420;\" \/><span class=\"su-slider-slide-title\">\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557<\/span><\/a><\/div><div class=\"su-slider-slide\"><a><img decoding=\"async\" data-src=\"https:\/\/larts.rmutp.ac.th\/2554\/wp-content\/uploads\/2015\/09\/\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19_3621-700x420.jpg\" alt=\"\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 700px; --smush-placeholder-aspect-ratio: 700\/420;\" \/><span class=\"su-slider-slide-title\">\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557<\/span><\/a><\/div><div class=\"su-slider-slide\"><a><img decoding=\"async\" data-src=\"https:\/\/larts.rmutp.ac.th\/2554\/wp-content\/uploads\/2015\/09\/\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19_9489-700x420.jpg\" alt=\"\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 700px; --smush-placeholder-aspect-ratio: 700\/420;\" \/><span class=\"su-slider-slide-title\">\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557<\/span><\/a><\/div><div class=\"su-slider-slide\"><a><img decoding=\"async\" data-src=\"https:\/\/larts.rmutp.ac.th\/2554\/wp-content\/uploads\/2015\/09\/\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19_4234-700x420.jpg\" alt=\"\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 700px; --smush-placeholder-aspect-ratio: 700\/420;\" \/><span class=\"su-slider-slide-title\">\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557<\/span><\/a><\/div><div class=\"su-slider-slide\"><a><img decoding=\"async\" data-src=\"https:\/\/larts.rmutp.ac.th\/2554\/wp-content\/uploads\/2015\/09\/\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19_4214-700x420.jpg\" alt=\"\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 700px; --smush-placeholder-aspect-ratio: 700\/420;\" \/><span class=\"su-slider-slide-title\">\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557<\/span><\/a><\/div><div class=\"su-slider-slide\"><a><img decoding=\"async\" data-src=\"https:\/\/larts.rmutp.ac.th\/2554\/wp-content\/uploads\/2015\/09\/\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19_1952-700x420.jpg\" alt=\"\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 700px; --smush-placeholder-aspect-ratio: 700\/420;\" \/><span class=\"su-slider-slide-title\">\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557<\/span><\/a><\/div><div class=\"su-slider-slide\"><a><img decoding=\"async\" data-src=\"https:\/\/larts.rmutp.ac.th\/2554\/wp-content\/uploads\/2015\/09\/\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19_174-700x420.jpg\" alt=\"\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 700px; --smush-placeholder-aspect-ratio: 700\/420;\" \/><span class=\"su-slider-slide-title\">\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557<\/span><\/a><\/div><div class=\"su-slider-slide\"><a><img decoding=\"async\" data-src=\"https:\/\/larts.rmutp.ac.th\/2554\/wp-content\/uploads\/2015\/09\/\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19_4398-700x420.jpg\" alt=\"\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" style=\"--smush-placeholder-width: 700px; --smush-placeholder-aspect-ratio: 700\/420;\" \/><span class=\"su-slider-slide-title\">\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e02\u0e32 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2557<\/span><\/a><\/div><\/div><div class=\"su-slider-nav\"><div class=\"su-slider-direction\"><span class=\"su-slider-prev\"><\/span><span class=\"su-slider-next\"><\/span><\/div><div class=\"su-slider-pagination\"><\/div><\/div><\/div>\n<p>\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e23\u0e49\u0e2d\u0e22\u0e15\u0e23\u0e35 \u0e27\u0e31\u0e0a\u0e23\u0e30 \u0e42\u0e1e\u0e18\u0e34\u0e2a\u0e23\u0e13\u0e4c \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e40\u0e1b\u0e34\u0e14\u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1b\u0e35\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 2557 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1c\u0e28.\u0e14\u0e23.\u0e40\u0e2a\u0e19\u0e35\u0e22\u0e4c \u0e1e\u0e27\u0e07\u0e22\u0e32\u0e13\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e39\u0e49\u0e17\u0e23\u0e07\u0e04\u0e38\u0e13\u0e27\u0e38\u0e12\u0e34\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e14\u0e23.\u0e13\u0e31\u0e10\u0e27\u0e34\u0e20\u0e32 \u0e27\u0e34\u0e23\u0e34\u0e22\u0e32 \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e41\u0e25\u0e30\u0e2d.\u0e1b\u0e20\u0e32\u0e14\u0e32 \u0e2a\u0e37\u0e1a\u0e1e\u0e25\u0e32\u0e22 \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 15-16 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2558 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2d\u0e32\u0e20\u0e32\u0e01\u0e23 \u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<\/p>\n<p>\u0e20\u0e32\u0e1e\u0e42\u0e14\u0e22 : \u0e07\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23 \u0e04\u0e13\u0e30\u0e28\u0e34\u0e25\u0e1b\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":8583,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[125],"class_list":["post-8575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1","tag-125"],"_links":{"self":[{"href":"https:\/\/larts.rmutp.ac.th\/2554\/wp-json\/wp\/v2\/posts\/8575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/larts.rmutp.ac.th\/2554\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/larts.rmutp.ac.th\/2554\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/larts.rmutp.ac.th\/2554\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/larts.rmutp.ac.th\/2554\/wp-json\/wp\/v2\/comments?post=8575"}],"version-history":[{"count":5,"href":"https:\/\/larts.rmutp.ac.th\/2554\/wp-json\/wp\/v2\/posts\/8575\/revisions"}],"predecessor-version":[{"id":8605,"href":"https:\/\/larts.rmutp.ac.th\/2554\/wp-json\/wp\/v2\/posts\/8575\/revisions\/8605"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/larts.rmutp.ac.th\/2554\/wp-json\/wp\/v2\/media\/8583"}],"wp:attachment":[{"href":"https:\/\/larts.rmutp.ac.th\/2554\/wp-json\/wp\/v2\/media?parent=8575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/larts.rmutp.ac.th\/2554\/wp-json\/wp\/v2\/categories?post=8575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/larts.rmutp.ac.th\/2554\/wp-json\/wp\/v2\/tags?post=8575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}